{"id":19390,"date":"2016-10-17T19:19:51","date_gmt":"2016-10-17T23:19:51","guid":{"rendered":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg"},"modified":"2016-10-17T19:22:07","modified_gmt":"2016-10-17T23:22:07","slug":"photographer-121","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/greatminds\/2016\/10\/17\/conquering-congress\/photographer-121\/","title":{"rendered":"Photographer"},"author":61,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":["post-19390","attachment","type-attachment","status-inherit","entry","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Photographer - Great Minds<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2016\\\/10\\\/Grace-5.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2016\\\/10\\\/Grace-5.jpg\",\"name\":\"Photographer - Great Minds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/#website\"},\"datePublished\":\"2016-10-17T23:19:51+00:00\",\"dateModified\":\"2016-10-17T23:22:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2016\\\/10\\\/Grace-5.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2016\\\/10\\\/Grace-5.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2016\\\/10\\\/Grace-5.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conquering Congress\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/2016\\\/10\\\/17\\\/conquering-congress\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Photographer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/\",\"name\":\"Great Minds\",\"description\":\"University of Mary Washington\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/greatminds\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Photographer - Great Minds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg","url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg","name":"Photographer - Great Minds","isPartOf":{"@id":"https:\/\/www.umw.edu\/greatminds\/#website"},"datePublished":"2016-10-17T23:19:51+00:00","dateModified":"2016-10-17T23:22:07+00:00","breadcrumb":{"@id":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umw.edu\/greatminds\/"},{"@type":"ListItem","position":2,"name":"Conquering Congress","item":"https:\/\/www.umw.edu\/greatminds\/2016\/10\/17\/conquering-congress\/"},{"@type":"ListItem","position":3,"name":"Photographer"}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/greatminds\/#website","url":"https:\/\/www.umw.edu\/greatminds\/","name":"Great Minds","description":"University of Mary Washington","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/greatminds\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"215\" src=\"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-300x215.jpg\" class=\"attachment-medium size-medium\" alt=\"Great mind feature, September 16, 2016. (Photo by Norm Shafer).\" srcset=\"\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-300x215.jpg 300w, \/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-768x549.jpg 768w, \/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1024x732.jpg 1024w, \/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1140x815.jpg 1140w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"19390\" data-permalink=\"https:\/\/www.umw.edu\/greatminds\/2016\/10\/17\/conquering-congress\/photographer-121\/\" data-orig-file=\"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg\" data-orig-size=\"3000,2145\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"2.2\",\"credit\":\"Norm Shafer\",\"camera\":\"\",\"caption\":\"Great mind feature, September 16, 2016.   (Photo by Norm Shafer).\",\"created_timestamp\":\"1473984000\",\"copyright\":\"Norm Shafer@2015\",\"focal_length\":\"16\",\"iso\":\"800\",\"shutter_speed\":\"0.0166666666667\",\"title\":\"Photographer\",\"orientation\":\"1\"}' data-image-title=\"Photographer\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1024x732.jpg\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Great mind feature, September 16, 2016. (Photo by Norm Shafer).","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3000,"height":2145,"file":"2016\/10\/Grace-5.jpg","sizes":{"thumbnail":{"file":"Grace-5-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-150x150.jpg"},"medium":{"file":"Grace-5-300x215.jpg","width":300,"height":215,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-300x215.jpg"},"medium_large":{"file":"Grace-5-768x549.jpg","width":768,"height":549,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-768x549.jpg"},"large":{"file":"Grace-5-1024x732.jpg","width":1024,"height":732,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1024x732.jpg"},"home-top":{"file":"Grace-5-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1140x460.jpg"},"home-bottom":{"file":"Grace-5-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-285x160.jpg"},"sidebar":{"file":"Grace-5-300x150.jpg","width":300,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-300x150.jpg"},"news-feature":{"file":"Grace-5-250x155.jpg","width":250,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-250x155.jpg"},"post-feature":{"file":"Grace-5-680x453.jpg","width":680,"height":453,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-680x453.jpg"},"post-feed-feature":{"file":"Grace-5-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-285x160.jpg"},"page-feature":{"file":"Grace-5-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1140x460.jpg"},"page-feature-uncropped":{"file":"Grace-5-1140x815.jpg","width":1140,"height":815,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-1140x815.jpg"},"sidebar-feature":{"file":"Grace-5-310x155.jpg","width":310,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-310x155.jpg"},"50px-thumb":{"file":"Grace-5-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-50x50.jpg"},"75px-thumb":{"file":"Grace-5-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5-75x75.jpg"},"full":{"file":"Grace-5.jpg","width":3000,"height":2145,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg"}},"image_meta":{"aperture":"2.2","credit":"Norm Shafer","camera":"","caption":"Great mind feature, September 16, 2016.   (Photo by Norm Shafer).","created_timestamp":"1473984000","copyright":"Norm Shafer@2015","focal_length":"16","iso":"800","shutter_speed":"0.0166666666667","title":"Photographer","orientation":"1","keywords":["Grace","Great Minds","Feature","diverse"]}},"post":19388,"source_url":"https:\/\/www.umw.edu\/greatminds\/wp-content\/uploads\/sites\/20\/2016\/10\/Grace-5.jpg","filename":"Grace-5.jpg","filesize":2090664,"_links":{"self":[{"href":"https:\/\/www.umw.edu\/greatminds\/wp-json\/wp\/v2\/media\/19390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/greatminds\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/greatminds\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/greatminds\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/greatminds\/wp-json\/wp\/v2\/comments?post=19390"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":19388,"href":"https:\/\/www.umw.edu\/greatminds\/wp-json\/wp\/v2\/posts\/19388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}