{"id":43041,"date":"2012-04-23T18:49:51","date_gmt":"2012-04-23T18:49:51","guid":{"rendered":"http:\/\/umwwebmaster.wpengine.com\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg"},"modified":"2012-04-23T18:49:51","modified_gmt":"2012-04-23T18:49:51","slug":"eve-watters","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/news\/eve-watters\/","title":{"rendered":"Eve Watters"},"author":61,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":["post-43041","attachment","type-attachment","status-inherit","entry","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eve Watters - News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eve Watters - News\" \/>\n<meta property=\"og:description\" content=\"Eve Watters\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofMaryWashington\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"1232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UMaryWash\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/04\\\/Eve-Watters.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/04\\\/Eve-Watters.jpg\",\"name\":\"Eve Watters - News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\"},\"datePublished\":\"2012-04-23T18:49:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/04\\\/Eve-Watters.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/04\\\/Eve-Watters.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/04\\\/Eve-Watters.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eve Watters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"name\":\"News\",\"description\":\"University of Mary Washington\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\",\"name\":\"University of Mary Washington\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"contentUrl\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"width\":2255,\"height\":580,\"caption\":\"University of Mary Washington\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofMaryWashington\\\/\",\"https:\\\/\\\/x.com\\\/UMaryWash\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eve Watters - News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg","og_locale":"en_US","og_type":"article","og_title":"Eve Watters - News","og_description":"Eve Watters","og_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg","og_site_name":"News","article_publisher":"https:\/\/www.facebook.com\/UniversityofMaryWashington\/","og_image":[{"width":852,"height":1232,"url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UMaryWash","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg","name":"Eve Watters - News","isPartOf":{"@id":"https:\/\/www.umw.edu\/news\/#website"},"datePublished":"2012-04-23T18:49:51+00:00","breadcrumb":{"@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umw.edu\/news\/"},{"@type":"ListItem","position":2,"name":"Eve Watters"}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/news\/#website","url":"https:\/\/www.umw.edu\/news\/","name":"News","description":"University of Mary Washington","publisher":{"@id":"https:\/\/www.umw.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.umw.edu\/news\/#organization","name":"University of Mary Washington","url":"https:\/\/www.umw.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","contentUrl":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","width":2255,"height":580,"caption":"University of Mary Washington"},"image":{"@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofMaryWashington\/","https:\/\/x.com\/UMaryWash"]}]}},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"207\" height=\"300\" src=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-207x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-207x300.jpg 207w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-768x1111.jpg 768w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-788x1140.jpg 788w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-415x600.jpg 415w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-708x1024.jpg 708w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg 852w\" sizes=\"auto, (max-width: 207px) 100vw, 207px\" data-attachment-id=\"43041\" data-permalink=\"https:\/\/www.umw.edu\/news\/eve-watters\/\" data-orig-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg\" data-orig-size=\"852,1232\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\"}' data-image-title=\"Eve Watters\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Eve Watters&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-708x1024.jpg\"><\/a><\/p>\n"},"caption":{"rendered":"<p>Eve Watters<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":852,"height":1232,"file":"2012\/04\/Eve-Watters.jpg","sizes":{"medium_large":{"file":"Eve-Watters-768x1111.jpg","width":768,"height":1111,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-768x1111.jpg"},"page-feature-uncropped":{"file":"Eve-Watters-788x1140.jpg","width":788,"height":1140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-788x1140.jpg"},"newsletter-feature":{"file":"Eve-Watters-415x600.jpg","width":415,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-415x600.jpg"},"thumbnail":{"file":"Eve-Watters-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-150x150.jpg"},"medium":{"file":"Eve-Watters-207x300.jpg","width":207,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-207x300.jpg"},"large":{"file":"Eve-Watters-708x1024.jpg","width":708,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-708x1024.jpg"},"home-top":{"file":"Eve-Watters-852x460.jpg","width":852,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-852x460.jpg"},"home-bottom":{"file":"Eve-Watters-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-285x160.jpg"},"sidebar":{"file":"Eve-Watters-300x150.jpg","width":300,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-300x150.jpg"},"news-feature":{"file":"Eve-Watters-250x155.jpg","width":250,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-250x155.jpg"},"post-feature":{"file":"Eve-Watters-680x453.jpg","width":680,"height":453,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-680x453.jpg"},"post-feed-feature":{"file":"Eve-Watters-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-285x160.jpg"},"page-feature":{"file":"Eve-Watters-852x460.jpg","width":852,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-852x460.jpg"},"sidebar-feature":{"file":"Eve-Watters-310x155.jpg","width":310,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-310x155.jpg"},"50px-thumb":{"file":"Eve-Watters-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-50x50.jpg"},"75px-thumb":{"file":"Eve-Watters-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters-75x75.jpg"},"full":{"file":"Eve-Watters.jpg","width":852,"height":1232,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/04\/Eve-Watters.jpg","filename":"Eve-Watters.jpg","filesize":614196,"_links":{"self":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media\/43041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/comments?post=43041"}]}}