{"id":53181,"date":"2012-10-22T15:18:20","date_gmt":"2012-10-22T19:18:20","guid":{"rendered":"http:\/\/umwwebmaster.wpengine.com\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry.jpg"},"modified":"2012-10-22T15:18:20","modified_gmt":"2012-10-22T19:18:20","slug":"benjerry-2","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/news\/benjerry-2\/","title":{"rendered":"BenJerry"},"author":65,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":["post-53181","attachment","type-attachment","status-inherit","entry","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BenJerry - News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BenJerry - News\" \/>\n<meta property=\"og:description\" content=\"Ben Cohen and Jerry Greenfield, co-founders of Ben &amp; Jerry\u2019s Homemade, Inc., will speak at UMW on November 10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofMaryWashington\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UMaryWash\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/10\\\/BenJerry-scaled.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/10\\\/BenJerry-scaled.jpg\",\"name\":\"BenJerry - News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\"},\"datePublished\":\"2012-10-22T19:18:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/10\\\/BenJerry-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/10\\\/BenJerry-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2012\\\/10\\\/BenJerry-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BenJerry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"name\":\"News\",\"description\":\"University of Mary Washington\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\",\"name\":\"University of Mary Washington\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"contentUrl\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"width\":2255,\"height\":580,\"caption\":\"University of Mary Washington\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofMaryWashington\\\/\",\"https:\\\/\\\/x.com\\\/UMaryWash\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BenJerry - News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"BenJerry - News","og_description":"Ben Cohen and Jerry Greenfield, co-founders of Ben &amp; Jerry\u2019s Homemade, Inc., will speak at UMW on November 10.","og_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg","og_site_name":"News","article_publisher":"https:\/\/www.facebook.com\/UniversityofMaryWashington\/","og_image":[{"width":2560,"height":1713,"url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UMaryWash","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg","name":"BenJerry - News","isPartOf":{"@id":"https:\/\/www.umw.edu\/news\/#website"},"datePublished":"2012-10-22T19:18:20+00:00","breadcrumb":{"@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umw.edu\/news\/"},{"@type":"ListItem","position":2,"name":"BenJerry"}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/news\/#website","url":"https:\/\/www.umw.edu\/news\/","name":"News","description":"University of Mary Washington","publisher":{"@id":"https:\/\/www.umw.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.umw.edu\/news\/#organization","name":"University of Mary Washington","url":"https:\/\/www.umw.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","contentUrl":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","width":2255,"height":580,"caption":"University of Mary Washington"},"image":{"@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofMaryWashington\/","https:\/\/x.com\/UMaryWash"]}]}},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-300x201.jpg 300w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1024x685.jpg 1024w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-768x514.jpg 768w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1536x1028.jpg 1536w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-2048x1370.jpg 2048w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-680x453.jpg 680w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1140x763.jpg 1140w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-600x402.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"53181\" data-permalink=\"https:\/\/www.umw.edu\/news\/benjerry-2\/\" data-orig-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg\" data-orig-size=\"2560,1713\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"6.7\",\"credit\":\"\",\"camera\":\"FinePix S3Pro\",\"caption\":\"\",\"created_timestamp\":\"1156170928\",\"copyright\":\"\",\"focal_length\":\"72\",\"iso\":\"200\",\"shutter_speed\":\"0.008\",\"title\":\"\",\"orientation\":\"1\"}' data-image-title=\"BenJerry\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ben Cohen and Jerry Greenfield, co-founders of Ben &amp;amp; Jerry&rsquo;s Homemade, Inc., will speak at UMW on November 10.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1024x685.jpg\"><\/a><\/p>\n"},"caption":{"rendered":"<p>Ben Cohen and Jerry Greenfield, co-founders of Ben &amp; Jerry\u2019s Homemade, Inc., will speak at UMW on November 10.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1713,"file":"2012\/10\/BenJerry-scaled.jpg","sizes":{"medium":{"file":"BenJerry-300x201.jpg","width":300,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-300x201.jpg"},"large":{"file":"BenJerry-1024x685.jpg","width":1024,"height":685,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1024x685.jpg"},"thumbnail":{"file":"BenJerry-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-150x150.jpg"},"medium_large":{"file":"BenJerry-768x514.jpg","width":768,"height":514,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-768x514.jpg"},"1536x1536":{"file":"BenJerry-1536x1028.jpg","width":1536,"height":1028,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1536x1028.jpg"},"2048x2048":{"file":"BenJerry-2048x1370.jpg","width":2048,"height":1370,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-2048x1370.jpg"},"home-top":{"file":"BenJerry-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1140x460.jpg"},"home-bottom":{"file":"BenJerry-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-285x160.jpg"},"sidebar":{"file":"BenJerry-300x150.jpg","width":300,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-300x150.jpg"},"news-feature":{"file":"BenJerry-250x155.jpg","width":250,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-250x155.jpg"},"post-feature":{"file":"BenJerry-680x453.jpg","width":680,"height":453,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-680x453.jpg"},"post-feed-feature":{"file":"BenJerry-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-285x160.jpg"},"page-feature":{"file":"BenJerry-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1140x460.jpg"},"page-feature-uncropped":{"file":"BenJerry-1140x763.jpg","width":1140,"height":763,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1140x763.jpg"},"sidebar-feature":{"file":"BenJerry-310x155.jpg","width":310,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-310x155.jpg"},"root-home-slideshow":{"file":"BenJerry-1140x570.jpg","width":1140,"height":570,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-1140x570.jpg"},"newsletter-feature":{"file":"BenJerry-600x402.jpg","width":600,"height":402,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-600x402.jpg"},"50px-thumb":{"file":"BenJerry-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-50x50.jpg"},"75px-thumb":{"file":"BenJerry-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-75x75.jpg"},"news-archive-feature":{"file":"BenJerry-860x430.jpg","width":860,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-860x430.jpg"},"full":{"file":"BenJerry-scaled.jpg","width":2560,"height":1713,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"FinePix S3Pro","caption":"","created_timestamp":"1156170928","copyright":"","focal_length":"72","iso":"200","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]},"original_image":"BenJerry.jpg"},"post":null,"source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2012\/10\/BenJerry-scaled.jpg","filename":"BenJerry.jpg","filesize":3581654,"_links":{"self":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media\/53181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/comments?post=53181"}]}}