{"id":86248,"date":"2015-11-19T15:41:36","date_gmt":"2015-11-19T20:41:36","guid":{"rendered":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg"},"modified":"2015-11-19T15:41:36","modified_gmt":"2015-11-19T20:41:36","slug":"anderson02_news","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/news\/2015\/11\/20\/umw-establishes-endowment-names-arena-to-honor-area-businessman\/anderson02_news\/","title":{"rendered":"anderson02_news"},"author":61,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","jetpack_post_was_ever_published":false,"_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":{"0":"post-86248","1":"attachment","2":"type-attachment","3":"status-inherit","5":"entry","6":"has-post-thumbnail"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>anderson02_news - News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"anderson02_news - News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofMaryWashington\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2280\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UMaryWash\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/11\\\/anderson02_news.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/11\\\/anderson02_news.jpg\",\"name\":\"anderson02_news - News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\"},\"datePublished\":\"2015-11-19T20:41:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/11\\\/anderson02_news.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/11\\\/anderson02_news.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/11\\\/anderson02_news.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UMW Establishes Endowment, Names Arena to Honor Area Businessman\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/2015\\\/11\\\/20\\\/umw-establishes-endowment-names-arena-to-honor-area-businessman\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"anderson02_news\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"name\":\"News\",\"description\":\"University of Mary Washington\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\",\"name\":\"University of Mary Washington\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"contentUrl\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"width\":2255,\"height\":580,\"caption\":\"University of Mary Washington\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofMaryWashington\\\/\",\"https:\\\/\\\/x.com\\\/UMaryWash\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"anderson02_news - News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg","og_locale":"en_US","og_type":"article","og_title":"anderson02_news - News","og_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg","og_site_name":"News","article_publisher":"https:\/\/www.facebook.com\/UniversityofMaryWashington\/","og_image":[{"width":2280,"height":920,"url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UMaryWash","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg","name":"anderson02_news - News","isPartOf":{"@id":"https:\/\/www.umw.edu\/news\/#website"},"datePublished":"2015-11-19T20:41:36+00:00","breadcrumb":{"@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umw.edu\/news\/"},{"@type":"ListItem","position":2,"name":"UMW Establishes Endowment, Names Arena to Honor Area Businessman","item":"https:\/\/www.umw.edu\/news\/2015\/11\/20\/umw-establishes-endowment-names-arena-to-honor-area-businessman\/"},{"@type":"ListItem","position":3,"name":"anderson02_news"}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/news\/#website","url":"https:\/\/www.umw.edu\/news\/","name":"News","description":"University of Mary Washington","publisher":{"@id":"https:\/\/www.umw.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.umw.edu\/news\/#organization","name":"University of Mary Washington","url":"https:\/\/www.umw.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","contentUrl":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","width":2255,"height":580,"caption":"University of Mary Washington"},"image":{"@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofMaryWashington\/","https:\/\/x.com\/UMaryWash"]}]}},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"121\" src=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-300x121.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-300x121.jpg 300w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1024x413.jpg 1024w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-768x310.jpg 768w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1536x620.jpg 1536w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-2048x826.jpg 2048w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1140x460.jpg 1140w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-600x242.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"86248\" data-permalink=\"https:\/\/www.umw.edu\/news\/2015\/11\/20\/umw-establishes-endowment-names-arena-to-honor-area-businessman\/anderson02_news\/\" data-orig-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg\" data-orig-size=\"2280,920\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\"}' data-image-title=\"anderson02_news\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-300x121.jpg\" data-large-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1024x413.jpg\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2280,"height":920,"file":"2015\/11\/anderson02_news.jpg","sizes":{"medium":{"file":"anderson02_news-300x121.jpg","width":300,"height":121,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-300x121.jpg"},"large":{"file":"anderson02_news-1024x413.jpg","width":1024,"height":413,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1024x413.jpg"},"thumbnail":{"file":"anderson02_news-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-150x150.jpg"},"medium_large":{"file":"anderson02_news-768x310.jpg","width":768,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-768x310.jpg"},"1536x1536":{"file":"anderson02_news-1536x620.jpg","width":1536,"height":620,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1536x620.jpg"},"2048x2048":{"file":"anderson02_news-2048x826.jpg","width":2048,"height":826,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-2048x826.jpg"},"home-top":{"file":"anderson02_news-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1140x460.jpg"},"home-bottom":{"file":"anderson02_news-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-285x160.jpg"},"sidebar":{"file":"anderson02_news-300x150.jpg","width":300,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-300x150.jpg"},"news-feature":{"file":"anderson02_news-250x155.jpg","width":250,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-250x155.jpg"},"post-feature":{"file":"anderson02_news-680x453.jpg","width":680,"height":453,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-680x453.jpg"},"post-feed-feature":{"file":"anderson02_news-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-285x160.jpg"},"page-feature":{"file":"anderson02_news-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1140x460.jpg"},"page-feature-uncropped":{"file":"anderson02_news-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1140x460.jpg"},"sidebar-feature":{"file":"anderson02_news-310x155.jpg","width":310,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-310x155.jpg"},"root-home-slideshow":{"file":"anderson02_news-1140x570.jpg","width":1140,"height":570,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-1140x570.jpg"},"newsletter-feature":{"file":"anderson02_news-600x242.jpg","width":600,"height":242,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-600x242.jpg"},"50px-thumb":{"file":"anderson02_news-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-50x50.jpg"},"75px-thumb":{"file":"anderson02_news-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-75x75.jpg"},"news-archive-feature":{"file":"anderson02_news-860x430.jpg","width":860,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news-860x430.jpg"},"full":{"file":"anderson02_news.jpg","width":2280,"height":920,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":86243,"source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2015\/11\/anderson02_news.jpg","_links":{"self":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media\/86248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/comments?post=86248"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":86243,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/posts\/86243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}