{"id":89344,"date":"2019-04-30T14:50:51","date_gmt":"2019-04-30T18:50:51","guid":{"rendered":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg"},"modified":"2019-05-01T12:26:02","modified_gmt":"2019-05-01T16:26:02","slug":"womengender028","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/news\/2019\/05\/01\/professors-psychology-of-women-text-is-one-for-the-books\/womengender028\/","title":{"rendered":"WomenGender028"},"author":90,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":["post-89344","attachment","type-attachment","status-inherit","entry","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>WomenGender028 - News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WomenGender028 - News\" \/>\n<meta property=\"og:description\" content=\"UMW students Alexandra Diviney (maroon sweater) and Ellie Benning paticipate in Professor Mindy Erchull&#039;s Psychology of Women class. The students in the course were the first to use the textbook, &quot;Psychology of Women &amp; Gender,&quot; written by Erchull and fellow UMW psychology professor Miriam Liss. Photos by Suzanne Carr Rossi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofMaryWashington\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-01T16:26:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UMaryWash\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/WomenGender028.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/WomenGender028.jpg\",\"name\":\"WomenGender028 - News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\"},\"datePublished\":\"2019-04-30T18:50:51+00:00\",\"dateModified\":\"2019-05-01T16:26:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/WomenGender028.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/WomenGender028.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/WomenGender028.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professors&#8217; Psychology Text Is One for the Books\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/2019\\\/05\\\/01\\\/professors-psychology-of-women-text-is-one-for-the-books\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WomenGender028\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"name\":\"News\",\"description\":\"University of Mary Washington\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\",\"name\":\"University of Mary Washington\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"contentUrl\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"width\":2255,\"height\":580,\"caption\":\"University of Mary Washington\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofMaryWashington\\\/\",\"https:\\\/\\\/x.com\\\/UMaryWash\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WomenGender028 - News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg","og_locale":"en_US","og_type":"article","og_title":"WomenGender028 - News","og_description":"UMW students Alexandra Diviney (maroon sweater) and Ellie Benning paticipate in Professor Mindy Erchull's Psychology of Women class. The students in the course were the first to use the textbook, \"Psychology of Women &amp; Gender,\" written by Erchull and fellow UMW psychology professor Miriam Liss. Photos by Suzanne Carr Rossi.","og_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg","og_site_name":"News","article_publisher":"https:\/\/www.facebook.com\/UniversityofMaryWashington\/","article_modified_time":"2019-05-01T16:26:02+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UMaryWash","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg","name":"WomenGender028 - News","isPartOf":{"@id":"https:\/\/www.umw.edu\/news\/#website"},"datePublished":"2019-04-30T18:50:51+00:00","dateModified":"2019-05-01T16:26:02+00:00","breadcrumb":{"@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umw.edu\/news\/"},{"@type":"ListItem","position":2,"name":"Professors&#8217; Psychology Text Is One for the Books","item":"https:\/\/www.umw.edu\/news\/2019\/05\/01\/professors-psychology-of-women-text-is-one-for-the-books\/"},{"@type":"ListItem","position":3,"name":"WomenGender028"}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/news\/#website","url":"https:\/\/www.umw.edu\/news\/","name":"News","description":"University of Mary Washington","publisher":{"@id":"https:\/\/www.umw.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.umw.edu\/news\/#organization","name":"University of Mary Washington","url":"https:\/\/www.umw.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","contentUrl":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","width":2255,"height":580,"caption":"University of Mary Washington"},"image":{"@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofMaryWashington\/","https:\/\/x.com\/UMaryWash"]}]}},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UMW students Alexandra Diviney (maroon sweater) and Ellie Benning paticipate in Professor Mindy Erchull's &quot;Psychology of Women&quot; class. The students in the course were the first to use the textbook, &quot;Psychology of Women &amp; Gender,&quot; written by Erchull and fellow UMW psychology professor Miriam Liss. Photos by Suzanne Carr Rossi.\" srcset=\"\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-300x200.jpg 300w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-768x512.jpg 768w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1024x683.jpg 1024w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-680x453.jpg 680w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1140x760.jpg 1140w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-600x400.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"89344\" data-permalink=\"https:\/\/www.umw.edu\/news\/2019\/05\/01\/professors-psychology-of-women-text-is-one-for-the-books\/womengender028\/\" data-orig-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg\" data-orig-size=\"6000,4000\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"4\",\"credit\":\"\",\"camera\":\"ILCE-7M3\",\"caption\":\"\",\"created_timestamp\":\"1553008893\",\"copyright\":\"\",\"focal_length\":\"25\",\"iso\":\"640\",\"shutter_speed\":\"0.00625\",\"title\":\"\",\"orientation\":\"1\"}' data-image-title=\"WomenGender028\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;UMW students Alexandra Diviney (maroon sweater) and Ellie Benning paticipate in Professor Mindy Erchull&amp;#8217;s Psychology of Women class. The students in the course were the first to use the textbook, &amp;#8220;Psychology of Women &amp;amp; Gender,&amp;#8221; written by Erchull and fellow UMW psychology professor Miriam Liss. Photos by Suzanne Carr Rossi.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1024x683.jpg\"><\/a><\/p>\n"},"caption":{"rendered":"<p>UMW students Alexandra Diviney (maroon sweater) and Ellie Benning paticipate in Professor Mindy Erchull&#8217;s Psychology of Women class. The students in the course were the first to use the textbook, &#8220;Psychology of Women &amp; Gender,&#8221; written by Erchull and fellow UMW psychology professor Miriam Liss. Photos by Suzanne Carr Rossi.<\/p>\n"},"alt_text":"UMW students Alexandra Diviney (maroon sweater) and Ellie Benning paticipate in Professor Mindy Erchull's \"Psychology of Women\" class. The students in the course were the first to use the textbook, \"Psychology of Women & Gender,\" written by Erchull and fellow UMW psychology professor Miriam Liss. Photos by Suzanne Carr Rossi.","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":6000,"height":4000,"file":"2019\/04\/WomenGender028.jpg","sizes":{"thumbnail":{"file":"WomenGender028-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-150x150.jpg"},"medium":{"file":"WomenGender028-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-300x200.jpg"},"medium_large":{"file":"WomenGender028-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-768x512.jpg"},"large":{"file":"WomenGender028-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1024x683.jpg"},"home-top":{"file":"WomenGender028-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1140x460.jpg"},"home-bottom":{"file":"WomenGender028-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-285x160.jpg"},"sidebar":{"file":"WomenGender028-300x150.jpg","width":300,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-300x150.jpg"},"news-feature":{"file":"WomenGender028-250x155.jpg","width":250,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-250x155.jpg"},"post-feature":{"file":"WomenGender028-680x453.jpg","width":680,"height":453,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-680x453.jpg"},"post-feed-feature":{"file":"WomenGender028-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-285x160.jpg"},"page-feature":{"file":"WomenGender028-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1140x460.jpg"},"page-feature-uncropped":{"file":"WomenGender028-1140x760.jpg","width":1140,"height":760,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1140x760.jpg"},"sidebar-feature":{"file":"WomenGender028-310x155.jpg","width":310,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-310x155.jpg"},"root-home-slideshow":{"file":"WomenGender028-1140x570.jpg","width":1140,"height":570,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-1140x570.jpg"},"newsletter-feature":{"file":"WomenGender028-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-600x400.jpg"},"50px-thumb":{"file":"WomenGender028-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-50x50.jpg"},"75px-thumb":{"file":"WomenGender028-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-75x75.jpg"},"news-archive-feature":{"file":"WomenGender028-860x430.jpg","width":860,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028-860x430.jpg"},"full":{"file":"WomenGender028.jpg","width":6000,"height":4000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"ILCE-7M3","caption":"","created_timestamp":"1553008893","copyright":"","focal_length":"25","iso":"640","shutter_speed":"0.00625","title":"","orientation":"1","keywords":[]}},"post":89335,"source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2019\/04\/WomenGender028.jpg","filename":"WomenGender028.jpg","filesize":19370083,"_links":{"self":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media\/89344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/comments?post=89344"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":89335,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/posts\/89335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}