{"id":92215,"date":"2021-11-19T09:35:19","date_gmt":"2021-11-19T14:35:19","guid":{"rendered":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16.jpg"},"modified":"2021-11-19T14:05:56","modified_gmt":"2021-11-19T19:05:56","slug":"jamesfarmer16","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/news\/jamesfarmer16\/","title":{"rendered":""},"author":1236,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","jetpack_post_was_ever_published":false,"_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":{"0":"post-92215","1":"attachment","2":"type-attachment","3":"status-inherit","5":"entry","6":"has-post-thumbnail"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>- News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- News\" \/>\n<meta property=\"og:description\" content=\"Student Government Association President Brianna Reaves spoke about how Dr. Farmer&#039;s teachings and legacy continue to impact today&#039;s Mary Washington students. Photo by Suzanne Carr Rossi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofMaryWashington\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-19T19:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1699\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UMaryWash\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/jamesfarmer16-scaled.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/jamesfarmer16-scaled.jpg\",\"name\":\"- News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\"},\"datePublished\":\"2021-11-19T14:35:19+00:00\",\"dateModified\":\"2021-11-19T19:05:56+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/jamesfarmer16-scaled.jpg\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"name\":\"News\",\"description\":\"University of Mary Washington\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\",\"name\":\"University of Mary Washington\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"contentUrl\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"width\":2255,\"height\":580,\"caption\":\"University of Mary Washington\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofMaryWashington\\\/\",\"https:\\\/\\\/x.com\\\/UMaryWash\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"- News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"- News","og_description":"Student Government Association President Brianna Reaves spoke about how Dr. Farmer's teachings and legacy continue to impact today's Mary Washington students. Photo by Suzanne Carr Rossi.","og_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg","og_site_name":"News","article_publisher":"https:\/\/www.facebook.com\/UniversityofMaryWashington\/","article_modified_time":"2021-11-19T19:05:56+00:00","og_image":[{"width":1699,"height":2560,"url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UMaryWash","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg","name":"- News","isPartOf":{"@id":"https:\/\/www.umw.edu\/news\/#website"},"datePublished":"2021-11-19T14:35:19+00:00","dateModified":"2021-11-19T19:05:56+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg"]}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/news\/#website","url":"https:\/\/www.umw.edu\/news\/","name":"News","description":"University of Mary Washington","publisher":{"@id":"https:\/\/www.umw.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.umw.edu\/news\/#organization","name":"University of Mary Washington","url":"https:\/\/www.umw.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","contentUrl":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","width":2255,"height":580,"caption":"University of Mary Washington"},"image":{"@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofMaryWashington\/","https:\/\/x.com\/UMaryWash"]}]}},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Student Government Association President Brianna Reaves spoke about how Dr. Farmer's teachings and legacy continues to impact today's students at Mary Washington. Photo by Suzanne Carr Rossi.\" srcset=\"\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-199x300.jpg 199w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-680x1024.jpg 680w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-768x1157.jpg 768w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1019x1536.jpg 1019w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1359x2048.jpg 1359w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-757x1140.jpg 757w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-398x600.jpg 398w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg 1699w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" data-attachment-id=\"92215\" data-permalink=\"https:\/\/www.umw.edu\/news\/jamesfarmer16\/\" data-orig-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg\" data-orig-size=\"1699,2560\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"5\",\"credit\":\"\",\"camera\":\"ILCE-7M3\",\"caption\":\"\",\"created_timestamp\":\"1637270042\",\"copyright\":\"\",\"focal_length\":\"194\",\"iso\":\"1250\",\"shutter_speed\":\"0.004\",\"title\":\"\",\"orientation\":\"1\"}' data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Student Government Association President Brianna Reaves spoke about how Dr. Farmer&amp;#8217;s teachings and legacy continue to impact today&amp;#8217;s Mary Washington students. Photo by Suzanne Carr Rossi. &lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-199x300.jpg\" data-large-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-680x1024.jpg\"><\/a><\/p>\n"},"caption":{"rendered":"<p>Student Government Association President Brianna Reaves spoke about how Dr. Farmer&#8217;s teachings and legacy continue to impact today&#8217;s Mary Washington students. Photo by Suzanne Carr Rossi. <\/p>\n"},"alt_text":"Student Government Association President Brianna Reaves spoke about how Dr. Farmer's teachings and legacy continues to impact today's students at Mary Washington. Photo by Suzanne Carr Rossi.","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1699,"height":2560,"file":"2021\/11\/jamesfarmer16-scaled.jpg","sizes":{"medium":{"file":"jamesfarmer16-199x300.jpg","width":199,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-199x300.jpg"},"large":{"file":"jamesfarmer16-680x1024.jpg","width":680,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-680x1024.jpg"},"thumbnail":{"file":"jamesfarmer16-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-150x150.jpg"},"medium_large":{"file":"jamesfarmer16-768x1157.jpg","width":768,"height":1157,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-768x1157.jpg"},"1536x1536":{"file":"jamesfarmer16-1019x1536.jpg","width":1019,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1019x1536.jpg"},"2048x2048":{"file":"jamesfarmer16-1359x2048.jpg","width":1359,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1359x2048.jpg"},"home-top":{"file":"jamesfarmer16-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1140x460.jpg"},"home-bottom":{"file":"jamesfarmer16-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-285x160.jpg"},"sidebar":{"file":"jamesfarmer16-300x150.jpg","width":300,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-300x150.jpg"},"news-feature":{"file":"jamesfarmer16-250x155.jpg","width":250,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-250x155.jpg"},"post-feature":{"file":"jamesfarmer16-680x453.jpg","width":680,"height":453,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-680x453.jpg"},"post-feed-feature":{"file":"jamesfarmer16-285x160.jpg","width":285,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-285x160.jpg"},"page-feature":{"file":"jamesfarmer16-1140x460.jpg","width":1140,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1140x460.jpg"},"page-feature-uncropped":{"file":"jamesfarmer16-757x1140.jpg","width":757,"height":1140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-757x1140.jpg"},"sidebar-feature":{"file":"jamesfarmer16-310x155.jpg","width":310,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-310x155.jpg"},"root-home-slideshow":{"file":"jamesfarmer16-1140x570.jpg","width":1140,"height":570,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-1140x570.jpg"},"newsletter-feature":{"file":"jamesfarmer16-398x600.jpg","width":398,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-398x600.jpg"},"50px-thumb":{"file":"jamesfarmer16-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-50x50.jpg"},"75px-thumb":{"file":"jamesfarmer16-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-75x75.jpg"},"news-archive-feature":{"file":"jamesfarmer16-860x430.jpg","width":860,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-860x430.jpg"},"full":{"file":"jamesfarmer16-scaled.jpg","width":1699,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg"}},"image_meta":{"aperture":"5","credit":"","camera":"ILCE-7M3","caption":"","created_timestamp":"1637270042","copyright":"","focal_length":"194","iso":"1250","shutter_speed":"0.004","title":"","orientation":"1","keywords":[]},"original_image":"jamesfarmer16.jpg"},"post":null,"source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/11\/jamesfarmer16-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media\/92215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/users\/1236"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/comments?post=92215"}]}}