{"id":94515,"date":"2023-11-16T14:32:33","date_gmt":"2023-11-16T19:32:33","guid":{"rendered":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg"},"modified":"2023-11-16T14:34:48","modified_gmt":"2023-11-16T19:34:48","slug":"caesars","status":"inherit","type":"attachment","link":"https:\/\/www.umw.edu\/news\/2023\/11\/16\/umws-great-lives-series-announces-2024-lecture-lineup\/caesars\/","title":{"rendered":"Caesars"},"author":89,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"umw_cb_additional_links":[[]],"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","jetpack_post_was_ever_published":false,"_advisory_expires_time":"","_advisory_meta_include":false,"_links_to":"","_links_to_target":""},"class_list":{"0":"post-94515","1":"attachment","2":"type-attachment","3":"status-inherit","5":"entry","6":"has-post-thumbnail"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Caesars - News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caesars - News\" \/>\n<meta property=\"og:description\" content=\"Ten Caesars\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofMaryWashington\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T19:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"232\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UMaryWash\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/Caesars.jpg\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/Caesars.jpg\",\"name\":\"Caesars - News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\"},\"datePublished\":\"2023-11-16T19:32:33+00:00\",\"dateModified\":\"2023-11-16T19:34:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/Caesars.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/Caesars.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/Caesars.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UMW\u2019s Great Lives Series Announces 2024 Lecture Lineup\",\"item\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/2023\\\/11\\\/16\\\/umws-great-lives-series-announces-2024-lecture-lineup\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caesars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"name\":\"News\",\"description\":\"University of Mary Washington\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#organization\",\"name\":\"University of Mary Washington\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"contentUrl\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/10\\\/2colorUMWprimarywordmark.png\",\"width\":2255,\"height\":580,\"caption\":\"University of Mary Washington\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umw.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofMaryWashington\\\/\",\"https:\\\/\\\/x.com\\\/UMaryWash\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Caesars - News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg","og_locale":"en_US","og_type":"article","og_title":"Caesars - News","og_description":"Ten Caesars","og_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg","og_site_name":"News","article_publisher":"https:\/\/www.facebook.com\/UniversityofMaryWashington\/","article_modified_time":"2023-11-16T19:34:48+00:00","og_image":[{"width":232,"height":350,"url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@UMaryWash","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg","name":"Caesars - News","isPartOf":{"@id":"https:\/\/www.umw.edu\/news\/#website"},"datePublished":"2023-11-16T19:32:33+00:00","dateModified":"2023-11-16T19:34:48+00:00","breadcrumb":{"@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umw.edu\/news\/"},{"@type":"ListItem","position":2,"name":"UMW\u2019s Great Lives Series Announces 2024 Lecture Lineup","item":"https:\/\/www.umw.edu\/news\/2023\/11\/16\/umws-great-lives-series-announces-2024-lecture-lineup\/"},{"@type":"ListItem","position":3,"name":"Caesars"}]},{"@type":"WebSite","@id":"https:\/\/www.umw.edu\/news\/#website","url":"https:\/\/www.umw.edu\/news\/","name":"News","description":"University of Mary Washington","publisher":{"@id":"https:\/\/www.umw.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umw.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.umw.edu\/news\/#organization","name":"University of Mary Washington","url":"https:\/\/www.umw.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","contentUrl":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2021\/10\/2colorUMWprimarywordmark.png","width":2255,"height":580,"caption":"University of Mary Washington"},"image":{"@id":"https:\/\/www.umw.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofMaryWashington\/","https:\/\/x.com\/UMaryWash"]}]}},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<?xml encoding=\"utf-8\" ?><p class=\"attachment\"><a href=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-199x300.jpg 199w, \/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg 232w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" data-attachment-id=\"94515\" data-permalink=\"https:\/\/www.umw.edu\/news\/2023\/11\/16\/umws-great-lives-series-announces-2024-lecture-lineup\/caesars\/\" data-orig-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg\" data-orig-size=\"232,350\" data-comments-opened=\"1\" data-image-meta='{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\"}' data-image-title=\"Caesars\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ten Caesars &lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-199x300.jpg\" data-large-file=\"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg\"><\/a><\/p>\n"},"caption":{"rendered":"<p>Ten Caesars <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":232,"height":350,"file":"2023\/11\/Caesars.jpg","filesize":14066,"sizes":{"medium":{"file":"Caesars-199x300.jpg","width":199,"height":300,"filesize":18553,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-199x300.jpg"},"thumbnail":{"file":"Caesars-150x150.jpg","width":150,"height":150,"filesize":8243,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-150x150.jpg"},"home-bottom":{"file":"Caesars-232x160.jpg","width":232,"height":160,"filesize":12436,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-232x160.jpg"},"sidebar":{"file":"Caesars-232x150.jpg","width":232,"height":150,"filesize":12566,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-232x150.jpg"},"umw-gallery-thumb":{"file":"Caesars-224x116.jpg","width":224,"height":116,"filesize":8283,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-224x116.jpg"},"50px-thumb":{"file":"Caesars-50x50.jpg","width":50,"height":50,"filesize":1429,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-50x50.jpg"},"75px-thumb":{"file":"Caesars-75x75.jpg","width":75,"height":75,"filesize":2559,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars-75x75.jpg"},"full":{"file":"Caesars.jpg","width":232,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":94503,"source_url":"https:\/\/www.umw.edu\/news\/wp-content\/uploads\/sites\/7\/2023\/11\/Caesars.jpg","_links":{"self":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media\/94515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/comments?post=94515"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":94503,"href":"https:\/\/www.umw.edu\/news\/wp-json\/wp\/v2\/posts\/94503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}